{"id":8952,"date":"2025-11-11T12:46:26","date_gmt":"2025-11-11T11:46:26","guid":{"rendered":"https:\/\/momentum.lu\/?p=8952"},"modified":"2025-11-11T13:10:35","modified_gmt":"2025-11-11T12:10:35","slug":"flash-marches-du-23-octobre-2025-2","status":"publish","type":"post","link":"https:\/\/momentum.lu\/es\/2025\/11\/11\/flash-marches-du-23-octobre-2025-2\/","title":{"rendered":"FLASH march\u00e9s du 10 novembre 2025"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8952\" class=\"elementor elementor-8952\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b3c0e0d elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"b3c0e0d\" data-element_type=\"section\" id=\"home-section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a49c522\" data-id=\"a49c522\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2bb43a elementor-widget elementor-widget-heading\" data-id=\"c2bb43a\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FLASH march\u00e9s du 10 novembre 2025 |<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87e1686 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87e1686\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76dcad0\" data-id=\"76dcad0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bed75e9 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"bed75e9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/momentum.lu\/actualites\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-left\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Actualit\u00e9s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-194389e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"194389e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-125f282\" data-id=\"125f282\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bafaa2 elementor-widget elementor-widget-text-editor\" data-id=\"1bafaa2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"font-weight: 400;\">Chers tous,<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00ab\u00a0\u00c7a passe\u00a0-pour le moment-\u00a0\u00bb\u00a0:<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">La r\u00e9solution du Shutdown am\u00e9ricain. Des 22 occurrences depuis 1976, c\u2019est celui qui historiquement aura dur\u00e9 le plus longtemps (41 jours), et donc co\u00fbt\u00e9 le plus cher : on estime \u00e0 15 milliards de USD par jour, avec, vu la dur\u00e9e, un impact n\u00e9gatif \u00e0 attendre sur la croissance am\u00e9ricaine. On nous refait n\u00e9anmoins le coup d\u2019une solution temporaire, prochaine \u00e9ch\u00e9ance en janvier 2026.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Dans le m\u00eame temps, l\u2019administration Trump devrait annoncer sous peu une d\u00e9r\u00e9gulation massive du secteur financier, au grand dam, bien entendu, des banques europ\u00e9ennes. A la poubelle, probablement, les r\u00e8gles de B\u00e2le III (qui \u00e9taient cens\u00e9es r\u00e9gir les banques \u00e0 travers le monde), et qui imposent, entre autres, un renforcement des fonds propres.<\/p><p style=\"font-weight: 400;\">On va aussi vers un all\u00e8gement de la surveillance des risques li\u00e9s aux risques climatiques, un all\u00e8gement sur les contraintes de capitaux propres li\u00e9es aux activit\u00e9s de march\u00e9s, bref de quoi redonner aux banques am\u00e9ricaines des capacit\u00e9s monstrueuses de cr\u00e9dit, que d\u2019aucuns \u00e9valuent \u00e0 2 600 milliards de USD&#8230; La f\u00eate risque de se poursuivre sur les march\u00e9s.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">La poursuite de la mont\u00e9e des march\u00e9s, am\u00e9ricains en t\u00eate et surtout Nasdaq. Il ne fallait pas plus que la fin du shutdown pour relancer les march\u00e9s aujourd\u2019hui, m\u00eame si on note tout de m\u00eame un certain essoufflement depuis quelques semaines. Les arbres ne montent pas au ciel, et c\u2019est particuli\u00e8rement le cas pour le secteur de l\u2019Intelligence Artificielle, qui atteint des valorisations stratosph\u00e9riques.<\/p><p style=\"font-weight: 400;\">D\u2019une certaine mani\u00e8re cela nous rappelle les march\u00e9s de 2000, sur l\u2019IT et la Tech, o\u00f9 les actions montaient quoi qu\u2019il se passait, avant que le jeu de carte ne s\u2019\u00e9croule. Il est int\u00e9ressant d\u2019ailleurs de lire, sur plusieurs semaines, la tonalit\u00e9 des m\u00e9dias \u00e9conomiques sur ce sujet de survalorisation.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Nvidia. Le bestiau vaut tout de m\u00eame autour de 5 000 milliards (oui, cinq mille milliards) de dollars US de capitalisation. Soit 2 fois la capitalisation de toute la bourse de Paris (!), ou 1,5 fois le PIB de la France !!! Aussi \u00e9tonnant que cela puisse para\u00eetre, l\u2019action ne vaut seulement que 42 fois ses b\u00e9n\u00e9fices 2025, et seulement 29,7 fois ceux de 2026. Mais le risque de concurrence accrue, voire de r\u00e9glementation antitrust existent.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">La d\u00e9gradation de la note de la dette de la France. Moody\u2019s a \u00e9t\u00e9 un peu plus cl\u00e9ment il y a 10 jours, se contentant d\u2019abaisser la perspective, et pas la note. On reste donc \u00ab AA-, avec perspective n\u00e9gative \u00bb. Le spread OAT fran\u00e7aise \u2013 Bund allemand \u00e0 10 ans reste bien brid\u00e9, autour de 78 points de base.<\/p><p style=\"font-weight: 400;\">Et il faut dire que la France est bien aid\u00e9e par la plupart des g\u00e9rants mondiaux de fonds, qui d\u00e9tiennent de la dette, bien souvent avec des crit\u00e8res o\u00f9 \u00ab\u00a02 des 3 agences de rating doivent avoir donn\u00e9 un minimum de AA- pour qu\u2019ils puissent investir\u00a0\u00bb. Vu que \u00e7a ne passe plus pour la France, et que lesdits g\u00e9rants auraient d\u00fb se d\u00e9barrasser des centaines de milliards de dette fran\u00e7aise qu\u2019ils d\u00e9tiennent, alors ils ont renvers\u00e9 le sujet\u00a0: la plupart ont cass\u00e9 ce thermom\u00e8tre pour abaisser ces crit\u00e8res, et hop \u00e7a rentre\u00a0! Nous vous mettons en annexe l\u2019article des Echos du 30 octobre dernier, vous expliquant le tripatouillage (pardon, la nouvelle vision strat\u00e9gique) des agences de notation.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00ab\u00a0\u00c7a\u00a0va pas passer\u00a0\u00bb ou \u00ab\u00a0\u00e7a risque de pas passer\u00a0\u00bb\u00a0:<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">L\u2019examen des droits de douane par la Cour supr\u00eame am\u00e9ricaine. Et l\u00e0, \u00ab c\u2019est pas gagn\u00e9 \u00bb pour Trump, sur 2 sujets : avoir invoqu\u00e9 l\u2019urgence de la situation ne suffit pas, et d\u2019autre part il est rappel\u00e9 que c\u2019est aux Chambres de fixer ce genre de \u00ab d\u00e9tails \u00bb, et certainement pas \u00e0 l\u2019ex\u00e9cutif, qui ne peut qu\u2019impulser. Le risque, c\u2019est un remboursement des droits de douane, estim\u00e9s \u00e0 ce jour \u00e0 80 \/ 100 milliards de USD, une paille. Sans compter l\u2019impact politique qu\u2019aurait une telle d\u00e9cision.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Dans le secteur automobile, 50 000 destructions d\u2019emplois en Allemagne et 40 000 en France. Et nos \u00e9lites de l\u2019Europe qui ne r\u00e9agissent toujours pas, alors qu\u2019arrive une vague de submersion des voitures chinoises, BYD en t\u00eate.<\/p><p style=\"font-weight: 400;\">Parce qu\u2019on se rend compte que ce sur ce sujet, comme sur tous les autres o\u00f9 il y a pu y avoir quelques vell\u00e9it\u00e9s de revenir en arri\u00e8re de la part de la Commission europ\u00e9enne, passer une loi dite \u00ab\u00a0omnibus\u00a0\u00bb pour simplifier cr\u00e9e encore plus de complications&#8230;<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">On se tourne du c\u00f4t\u00e9 des guignols de l\u2018Assembl\u00e9e nationale fran\u00e7aise, o\u00f9 tout n\u2019est que posture et o\u00f9 il n\u2019y en a pas un pour rattraper l\u2019autre. C\u2019est la surench\u00e8re permanente, \u00e7a vitup\u00e8re dans tous les sens, c\u2019est le concours L\u00e9pine des id\u00e9es saugrenues, et surtout beaucoup de postures des partis politiques en vue des prochaines \u00e9lections. On devrait faire comme pour l\u2019\u00e9lection du Pape : un conclave, o\u00f9 l\u2019origine remonte aux cardinaux qui n\u2019arrivaient pas \u00e0 se mettre d\u2019accord, alors on les a enferm\u00e9s jusqu\u2019\u00e0 ce qu\u2019\u00e9lection s\u2019ensuive.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Tout en sachant que\u00a0:<\/p><p style=\"font-weight: 400;\">Le budget \u00ab d\u00e9penses \u00bb de l\u2019Etat n\u2019a toujours pas \u00e9t\u00e9 pass\u00e9 \u00e0 la question. Mais puisque on a mont\u00e9 les imp\u00f4ts et taxes de presque 40 milliards, l\u2019id\u00e9e doit \u00eatre qu\u2019alors, on peut probablement se passer de faire des \u00e9conomies.<\/p><p style=\"font-weight: 400;\">Bon, admettons que \u00e7a passe. Ca part au S\u00e9nat. Et l\u00e0, \u00ab selon toute logique \u00bb, \u00e7a va pas passer.<\/p><p style=\"font-weight: 400;\">Alors, Commission mixte paritaire, et vu les \u00e9carts id\u00e9ologiques entre l\u2019Assembl\u00e9e nationale et le S\u00e9nat, \u00ab c\u2019est pas gagn\u00e9 d\u2019avance \u00bb. Sachant qu\u2019en cas de d\u00e9saccord, le dernier mot revient \u00e0 l\u2019Assembl\u00e9e nationale.<\/p><p style=\"font-weight: 400;\">Bref on aura peut-\u00eatre un budget 2026 en 2027, ou, dans un avenir plus proche, un renversement du gouvernement Lecornu II\u00a0!<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Vous pouvez retrouver l\u2019historique de nos billets sur notre page LinkedIn\u00a0<a href=\"https:\/\/www.linkedin.com\/company\/momentum-asset-management\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.linkedin.com\/company\/momentum-asset-management\/<\/a>.<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">A votre disposition pour en rediscuter,<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Bien \u00e0 vous,<\/p><p style=\"font-weight: 400;\">\u00a0<\/p><p style=\"font-weight: 400;\">Pierre<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-39e1646\" data-id=\"39e1646\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad70612 elementor-widget elementor-widget-shortcode\" data-id=\"ad70612\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe src=\"https:\/\/www.linkedin.com\/embed\/feed\/update\/urn:li:ugcPost:7393734315899113472?collapsed=1\" height=\"566\" width=\"504\" frameborder=\"0\" allowfullscreen=\"\" title=\"Post int\u00e9gr\u00e9\"><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49d4173 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"49d4173\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.linkedin.com\/posts\/momentum-asset-management_flash-march%C3%A9s-du-10-novembre-2025-activity-7393734316930912256-fMEo?utm_source=share&#038;utm_medium=member_desktop&#038;rcm=ACoAACrTFKsBb7Pg6vA1gnxsMVZN6Dp_FQMyQf4\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir l'article<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-370d83b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"370d83b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a0793a\" data-id=\"3a0793a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b605457 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b605457\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8291add elementor-post-navigation-borders-yes elementor-widget elementor-widget-post-navigation\" data-id=\"8291add\" data-element_type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navegaci\u00f3n de la entrada\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/momentum.lu\/es\/2025\/10\/23\/flash-marches-du-10-novembre-2025\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><span class=\"elementor-screen-only\">Ant<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Pr\u00e9c\u00e9dent<\/span><span class=\"post-navigation__prev--title\">FLASH march\u00e9s du 23 octobre 2025<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation__separator-wrapper\">\n\t\t\t\t\t<div class=\"elementor-post-navigation__separator\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/momentum.lu\/es\/2025\/11\/25\/flash-marches-du-24-novembre-2025\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Suivant<\/span><span class=\"post-navigation__next--title\">FLASH march\u00e9s du 24 novembre 2025<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><span class=\"elementor-screen-only\">Siguiente<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60b733d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60b733d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6f1fb5\" data-id=\"f6f1fb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-919457f elementor-widget elementor-widget-heading\" data-id=\"919457f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partager<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eed8b3e elementor-share-buttons--view-icon elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"eed8b3e\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartici\u00f3 en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartici\u00f3 en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartici\u00f3 en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c5ee64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c5ee64\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-90099ab elementor-invisible\" data-id=\"90099ab\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bcf250 elementor-widget elementor-widget-text-editor\" data-id=\"1bcf250\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette note vous est envoy\u00e9e \u00e0 titre gratuit.&nbsp;<\/p>\n<p>Si vous souhaitez recevoir nos \u00ab points hebdomadaires \u00bb par mail, merci de nous l\u2019indiquer :<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9910ac2 pp-icon-list-traditional elementor-list-item-link-inline pp-icon-left elementor-widget elementor-widget-pp-icon-list\" data-id=\"9910ac2\" data-element_type=\"widget\" data-widget_type=\"pp-icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-list-container\">\n\t\t\t<ul class=\"pp-list-items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"pp-icon-list-item elementor-repeater-item-9ec806f\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:contact@momentum.lu\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-icon pp-icon \">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i><\/span>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"pp-icon-list-text\">\n\t\t\t\t\t\t\t\tcontact@momentum.lu\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d45d84a\" data-id=\"d45d84a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-364762f elementor-widget elementor-widget-heading\" data-id=\"364762f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Informations importantes sur la note : <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08520dd elementor-widget elementor-widget-pp-modal-popup\" data-id=\"08520dd\" data-element_type=\"widget\" data-settings=\"{&quot;content_close&quot;:&quot;yes&quot;,&quot;layout_type&quot;:&quot;standard&quot;,&quot;trigger&quot;:&quot;on-click&quot;,&quot;prevent_scroll&quot;:&quot;yes&quot;,&quot;close_button&quot;:&quot;yes&quot;,&quot;esc_exit&quot;:&quot;yes&quot;,&quot;click_exit&quot;:&quot;yes&quot;,&quot;popup_animation_in&quot;:&quot;mfp-zoom-in&quot;,&quot;overlay_switch&quot;:&quot;yes&quot;,&quot;close_button_position&quot;:&quot;win-top-right&quot;}\" data-widget_type=\"pp-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-modal-popup-wrap\" id=\"pp-modal-popup-wrap-08520dd\">\n\t\t\t<div class=\"pp-modal-popup\" data-src=\"#pp-modal-popup-window-08520dd\" data-popup-settings=\"{&quot;popupType&quot;:&quot;inline&quot;,&quot;src&quot;:&quot;#pp-modal-popup-window-08520dd&quot;,&quot;triggerElement&quot;:&quot;.pp-modal-popup-link-08520dd&quot;}\">\n\t\t\t\t<div class=\"pp-modal-popup-button-wrap elementor-align-center\"><span class=\"pp-modal-popup-button pp-modal-popup-link pp-modal-popup-link-08520dd elementor-button elementor-size-sm\"><span >vOIR INFOS<\/span>\t\t\t<span class=\"pp-button-icon pp-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-info-circle\"><\/i>\t\t\t<\/span>\n\t\t\t<\/span><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"pp-modal-popup-window pp-modal-popup-window-08520dd\" id=\"pp-modal-popup-window-08520dd\">\n\t\t\t\t<div class=\"pp-popup-content\" id=\"pp-popup-content\"><p><em>Les informations et donn\u00e9es indiqu\u00e9es, les opinions, avis, et remarques exprim\u00e9s sur ce site sont propos\u00e9s aux personnes qui le consultent \u00e0 titre d'information uniquement.\u00a0 <\/em><\/p>\n<p><em>Ils sont repris sans aucune garantie - qu'elle soit de nature explicite ou implicite - ni engagement quant \u00e0 leur caract\u00e8re exhaustif, leur pr\u00e9cision ou leur actualisation.\u00a0 <\/em><\/p>\n<p><em>Ils ne constituent pas une offre, une d\u00e9marche de commercialisation ou de recommandation, une sollicitation \u00e0 acheter, vendre, contracter ou souscrire \u00e0 un service ou produit financier quel qu'il soit.\u00a0 <\/em><\/p>\n<p><em>Ils ne constituent pas davantage un avis ou conseil juridique, financier, comptable ou autre.\u00a0 Ils ne se substituent en aucun cas aux consid\u00e9rations personnelles du visiteur, \u00e0 ses connaissances techniques, ou encore, \u00e0 ses comp\u00e9tences professionnelles. <\/em><\/p>\n<p><em>Les informations et donn\u00e9es doivent donc \u00eatre utilis\u00e9es avec les conseils d'un professionnel <\/em><\/p>\n<p><em>qualifi\u00e9\u00a0\u00a0 -\u00a0\u00a0 Voir aussi sur notre site <a href=\"https:\/\/www.momentum.lu\/e-mail-disclaimer\/\"><u>https:\/\/www.momentum.lu\/e-mail-disclaimer\/<\/u><\/a><\/em><\/p>\n<\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FLASH march\u00e9s du 10 novembre 2025 | Actualit\u00e9s Chers tous, \u00a0 \u00a0 \u00ab\u00a0\u00c7a passe\u00a0-pour le moment-\u00a0\u00bb\u00a0: \u00a0 La r\u00e9solution du Shutdown am\u00e9ricain. Des 22 occurrences depuis 1976, c\u2019est celui qui historiquement aura dur\u00e9 le plus longtemps (41 jours), et donc co\u00fbt\u00e9 le plus cher : on estime \u00e0 15 milliards de USD par jour, avec, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8953,"comment_status":"open","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"FLASH march\u00e9s du 10 novembre 2025 - Momentum","_seopress_titles_desc":"La r\u00e9solution du Shutdown am\u00e9ricain. Des 22 occurrences depuis 1976, c\u2019est celui qui historiquement aura dur\u00e9 le plus longtemps (41 jours)","_seopress_robots_index":"","inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-8952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-28"],"_links":{"self":[{"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/posts\/8952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/comments?post=8952"}],"version-history":[{"count":5,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/posts\/8952\/revisions"}],"predecessor-version":[{"id":8962,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/posts\/8952\/revisions\/8962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/media?parent=8952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/categories?post=8952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/momentum.lu\/es\/wp-json\/wp\/v2\/tags?post=8952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}